{"id":1777,"date":"2004-10-01T01:00:00","date_gmt":"2004-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/"},"modified":"2018-10-20T18:39:34","modified_gmt":"2018-10-20T16:39:34","slug":"mdr3-un-gene-pour-trois-maladies","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/","title":{"rendered":"MDR3 : UN GENE POUR TROIS MALADIES"},"content":{"rendered":"<p><strong>2004<\/strong><\/p>\n<p><em>Serge Erlinger (Aix en Provence)<\/em><\/p>\n<p><strong>H\u00e9patologie <\/strong>&#8211; \u00a02004-09-14 &#8211;\u00a0CF &#8211;<\/p>\n<p>________________________________<\/p>\n<p>Le g\u00e8ne MDR3 (ou ABCB4), localis\u00e9 sur le bras long du chromosome 7, code une glycoprot\u00e9ine de la membrane canaliculaire de l\u2019h\u00e9patocyte qui transporte le principal phospholipide biliaire, la phosphatidyl choline, dans la bile. Trois maladies sont li\u00e9es \u00e0 des mutations de ce g\u00e8ne.<br \/>\nLa cholestase intra-h\u00e9patique familiale de type 3 se manifeste chez le nouveau-n\u00e9, souvent au cours de la premi\u00e8re ann\u00e9e, l\u2019enfant ou l\u2019adulte jeune. Elle se caract\u00e9rise par un prurit, un ict\u00e8re, une augmentation importante de la &#947;-GT et, \u00e0 l\u2019examen histologique, une tr\u00e8s remarquable prolif\u00e9ration de n\u00e9o-ductules biliaires. Les l\u00e9sions \u00e9voluent vers une fibrose puis une cirrhose biliaire avec hypertension portale et h\u00e9morragies digestives. Dans une s\u00e9rie de 31 cas, une transplantation h\u00e9patique a \u00e9t\u00e9 effectu\u00e9e chez 18 patients \u00e0 l\u2019\u00e2ge moyen de 7,5 ans. La transmission se fait sur le mode autosomique r\u00e9cessif (les parents sont h\u00e9t\u00e9rozygotes) mais certaines mutations portant apparemment sur un seul all\u00e8le peuvent \u00eatre \u00e0 l\u2019origine de la maladie. Cette forme de cholestase familiale est distincte des types 1 (d\u00fb \u00e0 une mutation d\u2019une ATPase membranaire responsable du maintien de l\u2019asym\u00e9trie de la membrane) et 2 (d\u00fb \u00e0 une mutation du transporteur canaliculaire des acides biliaires).<br \/>\nLa cholestase gravidique est caract\u00e9ris\u00e9e par un prurit apparaissant au cours de la seconde moiti\u00e9 de la grossesse, progressif, avec parfois un ict\u00e8re, et souvent une souffrance f\u0153tale, un accouchement pr\u00e9matur\u00e9, voire un d\u00e9c\u00e8s in utero au troisi\u00e8me trimestre. La &#947;-GT s\u00e9rique est souvent normale, mais elle est augment\u00e9e dans un sous-groupe de patientes. Des cas familiaux ont \u00e9t\u00e9 d\u00e9crits, ainsi qu\u2019un prurit apparaissant lors de la prise d\u2019oestro-progestatifs. Dans plusieurs familles, il a \u00e9t\u00e9 montr\u00e9 que des m\u00e8res atteintes de ce syndrome \u00e9taient porteuses d\u2019une mutation de MDR3 \u00e0 l\u2019\u00e9tat h\u00e9t\u00e9rozygote et que les enfants \u00e9taient atteints de cholestase intra-h\u00e9patique familiale de type 3. On peut postuler que des mutations h\u00e9t\u00e9rozygotes des autres g\u00e8nes responsables de cholestase intra-h\u00e9patique familiale (types 1 et 2) pourraient \u00eatre \u00e0 l\u2019origine de la cholestase gravidique dans d\u2019autres familles.<br \/>\nLa lithiase intra-h\u00e9patique ou v\u00e9siculaire cholest\u00e9rolique est \u00e9galement, dans certains cas, la cons\u00e9quence de mutations de MDR3.  Le syndrome doit \u00eatre \u00e9voqu\u00e9 lorsque l\u2019un des 5 crit\u00e8res suivants est pr\u00e9sent : \u00e2ge inf\u00e9rieur \u00e0 40 ans aux premiers sympt\u00f4mes, r\u00e9cidive des sympt\u00f4mes apr\u00e8s chol\u00e9cystectomie, lithiase intra-h\u00e9patique ou \u00ab sludge \u00bb intra-h\u00e9patique, histoire familiale de lithiase, ant\u00e9c\u00e9dent de cholestase gravidique.<br \/>\nDans ces trois affections, l\u2019acide ursod\u00e9soxycholique a \u00e9t\u00e9 montr\u00e9 efficace. <\/p>\n<p>R\u00e9f\u00e9rences<br \/>\nErlinger S. G\u00e9n\u00e9tique mol\u00e9culaire des cholestases familiales. H\u00e9pato-Gastro, 2001 ; 8 : 287-292.<br \/>\nJacquemin E. Role of multidrug resistance 3 deficiency in pediatric and adult liver disease. Seminars in Liver Disease, 2001: 21 : 551-562.<br \/>\nRosmorduc O, Hermelin B, Boelle P-Y, et al.  ABCB4 gene mutation-associated cholelithiasis in adults. Gastroenterology 2003; 125 :  452-459.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2004 Serge Erlinger (Aix en Provence) H\u00e9patologie &#8211; \u00a02004-09-14 &#8211;\u00a0CF &#8211; ________________________________ Le g\u00e8ne MDR3 (ou ABCB4), localis\u00e9 sur le bras long du chromosome 7, code une glycoprot\u00e9ine de la membrane canaliculaire de l\u2019h\u00e9patocyte qui transporte le principal phospholipide biliaire, la phosphatidyl choline, dans la bile. Trois maladies sont li\u00e9es \u00e0 des mutations de ce [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[15],"class_list":["post-1777","post","type-post","status-publish","format-standard","hentry","category-hepatologie","tag-15"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:39:34+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"MDR3 : UN GENE POUR TROIS MALADIES\",\"datePublished\":\"2004-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2004\"],\"articleSection\":[\"Hepatologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/\",\"name\":\"MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2004-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:39:34+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/mdr3-un-gene-pour-trois-maladies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MDR3 : UN GENE POUR TROIS MALADIES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/","og_locale":"fr_FR","og_type":"article","og_title":"MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2004-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:39:34+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"MDR3 : UN GENE POUR TROIS MALADIES","datePublished":"2004-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2004"],"articleSection":["Hepatologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/","url":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/","name":"MDR3 : UN GENE POUR TROIS MALADIES - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2004-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:39:34+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/mdr3-un-gene-pour-trois-maladies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"MDR3 : UN GENE POUR TROIS MALADIES"}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}