{"id":1874,"date":"2009-10-01T01:00:00","date_gmt":"2009-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/"},"modified":"2018-10-20T18:39:51","modified_gmt":"2018-10-20T16:39:51","slug":"etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/","title":{"rendered":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas."},"content":{"rendered":"<p><strong>2009<\/strong><\/p>\n<p><em>I Rosa, J. Denis, P, Renard, AS Dobrin, R Faroux, C Becker, X Causse, R Bader, G Ledr\u00e9au, F Zerouala, E Diaz, J Henrion, O Danne, AJ R\u00e9my, B Nalet, T Morin, C Renou, H Hag\u00e8ge et le groupe d\u2019\u00e9tude CHANGH.<\/em><\/p>\n<p><strong>H\u00e9patologie <\/strong>&#8211; \u00a02009-07-07 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>Le carcinome h\u00e9pato-cellulaire (CHC) est responsable de 7000 d\u00e9c\u00e8s par an en France. Sa pr\u00e9valence est en forte augmentation, en partie en raison de l\u2019\u00e9volution des h\u00e9patites virales chroniques, mais \u00e9galement d\u2019un allongement de la survie des patients cirrhotiques et d\u2019un meilleur suivi.<\/p>\n<p>Le but de l\u2019observatoire CHANGH \u00e9tait d\u2019\u00e9valuer sur une large cohorte, la survie des patients ayant un CHC de novo et d\u2019en d\u00e9finir les facteurs pronostics. Les objectifs secondaires \u00e9taient de d\u00e9crire l\u2019\u00e9pid\u00e9miologie actuelle du CHC en France, les modalit\u00e9s de prise en charge et d\u2019\u00e9valuer les pratiques professionnelles.<br \/>\nCent trois h\u00f4pitaux (94 centres de l\u2019ANGH, 4 h\u00f4pitaux militaires et 5 CHU) ont particip\u00e9 \u00e0 cette \u00e9tude observationnelle prospective. Les inclusions ont  d\u00e9but\u00e9 le 1er mai 2008 et seront prolong\u00e9es jusqu\u2019au 30 octobre 2009 afin d\u2019atteindre un objectif de 1000 patients inclus. Nous pr\u00e9sentons ici les r\u00e9sultats pr\u00e9liminaires sur les 325 premi\u00e8res observations compl\u00e8tes re\u00e7ues au 1er juin 2009.<\/p>\n<p>Malades et m\u00e9thodes :<\/p>\n<p>Les crit\u00e8res d\u2019inclusion \u00e9taient la survenue de novo d\u2019un CHC, soit histologiquement prouv\u00e9, soit remplissant les crit\u00e8res radiologiques de Barcelone. Apr\u00e8s inclusion et description des donn\u00e9es initiales, un suivi annuel \u00e9tait mis en place pour une dur\u00e9e de 5 ans.<br \/>\nR\u00e9sultats :<br \/>\n784 fiches d\u2019inclusion ont \u00e9t\u00e9 re\u00e7ues et 325 dossiers complets renvoy\u00e9s. Dans 25% des cas, le diagnostic de CHC \u00e9tait histologique et dans 75% des cas radiologique. Le CHC survenait dans 77% des cas sur foie cirrhotique. L\u2019\u00e9tiologie de la cirrhose \u00e9tait l\u2019alcool dans 68% des cas, alors que la NASH repr\u00e9sentait la 2\u00e8me cause d\u2019h\u00e9patopathie chronique (18%). L\u2019h\u00e9patite chronique C et B \u00e9taient responsables respectivement de 15% et 10% des cirrhoses.<br \/>\nLes patients \u00e9taient class\u00e9s Child A, B ou C dans respectivement 43, 36 et 21% des cas. La l\u00e9sion \u00e9tait unique dans  38 % des cas. Il existait entre 1 et 3  l\u00e9sions dans 22% des cas, un CHC multifocal dans 29 % des cas et une infiltration diffuse du foie dans 11% des cas. Une thrombose portale \u00e9tait pr\u00e9sente dans 29% des cas et 15% des patients \u00e9taient m\u00e9tastatiques au moment du diagnostic.<br \/>\n87% des cas ont \u00e9t\u00e9 pr\u00e9sent\u00e9s en r\u00e9union de concertation pluridisciplinaire. Une r\u00e9section chirurgicale a \u00e9t\u00e9 propos\u00e9e dans 10% des cas, une radiofr\u00e9quence (RF) dans 8,5% des cas et une chimioembolisation (CE) dans 13% des cas. Une THO \u00e9tait propos\u00e9e dans 8,5% des cas et accept\u00e9e \u00e0 ce jour chez la moiti\u00e9 des patients, avec un traitement d\u2019attente par RF ou CE.<br \/>\nLe Soraf\u00e9nib a \u00e9t\u00e9 prescrit chez 61 patients, soit 19% des cas. Seul un traitement symptomatique a pu \u00eatre propos\u00e9 chez 134 patients (41%).<br \/>\n115 fiches de d\u00e9c\u00e8s ont \u00e9t\u00e9 re\u00e7ues \u00e0 un an. La cause du d\u00e9c\u00e8s \u00e9tait dans 90% des cas li\u00e9e au CHC ou \u00e0 la cirrhose.<\/p>\n<p>Conclusion :<br \/>\nSur ces r\u00e9sultats pr\u00e9liminaires, le CHC est responsable d\u2019une mortalit\u00e9 tr\u00e8s \u00e9lev\u00e9e. La premi\u00e8re cause d\u2019h\u00e9patopathie sous-jacente reste l\u2019alcool, mais actuellement la NASH appara\u00eet comme la deuxi\u00e8me cause, devan\u00e7ant les h\u00e9patites virales B et C. Malgr\u00e9 un meilleur d\u00e9pistage et un meilleur arsenal th\u00e9rapeutique, seul un traitement symptomatique a pu \u00eatre propos\u00e9 dans la majorit\u00e9 des cas, traduisant un diagnostic port\u00e9 \u00e0 un stade encore souvent trop avanc\u00e9. Ces donn\u00e9es seront compl\u00e9t\u00e9es par les r\u00e9sultats de l\u2019ensemble de la cohorte CHANGH.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2009 I Rosa, J. Denis, P, Renard, AS Dobrin, R Faroux, C Becker, X Causse, R Bader, G Ledr\u00e9au, F Zerouala, E Diaz, J Henrion, O Danne, AJ R\u00e9my, B Nalet, T Morin, C Renou, H Hag\u00e8ge et le groupe d\u2019\u00e9tude CHANGH. H\u00e9patologie &#8211; \u00a02009-07-07 &#8211;\u00a0CO &#8211; ________________________________ Le carcinome h\u00e9pato-cellulaire (CHC) est responsable de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[20],"class_list":["post-1874","post","type-post","status-publish","format-standard","hentry","category-hepatologie","tag-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:39:51+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas.\",\"datePublished\":\"2009-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:39:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/\"},\"wordCount\":656,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2009\"],\"articleSection\":[\"Hepatologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/\",\"name\":\"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2009-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:39:51+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/","og_locale":"fr_FR","og_type":"article","og_title":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2009-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:39:51+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas.","datePublished":"2009-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:39:51+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/"},"wordCount":656,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2009"],"articleSection":["Hepatologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/","url":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/","name":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2009-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:39:51+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/etude-longitudinale-descriptive-de-la-prise-en-charge-des-chc-dans-les-hopitaux-generaux-en-france-changh-resultats-preliminaires-sur-325-cas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"Etude longitudinale descriptive de la prise en charge des CHC dans les h\u00f4pitaux g\u00e9n\u00e9raux en France : CHANGH : r\u00e9sultats pr\u00e9liminaires sur 325 cas."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=1874"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1874\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=1874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=1874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=1874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}