{"id":1946,"date":"2011-10-01T01:00:00","date_gmt":"2011-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/"},"modified":"2018-10-20T18:40:04","modified_gmt":"2018-10-20T16:40:04","slug":"atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/","title":{"rendered":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente."},"content":{"rendered":"<p><strong>2011<\/strong><\/p>\n<p><em>Jean Henrion, Pierre Deltenre, St\u00e9phane De Maeght.<br \/>\nService d\u2019H\u00e9pato-Gastroent\u00e9rologie, H\u00f4pital de Jolimont, Haine-Saint-Paul, Belgique<\/em><\/p>\n<p><strong>H\u00e9patologie <\/strong>&#8211; \u00a02011-05-19 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>L\u2019histoire naturelle de la HAA est mieux connue gr\u00e2ce aux travaux de l\u2019\u00e9quipe lilloise. La mortalit\u00e9 \u00e0 six semaines est de l\u2019ordre de 25 % et est pr\u00e9dite par le score de Lille (1). La survie \u00e0 cinq ans est de l\u2019ordre de 30 % et d\u00e9pend de l\u2019abstinence (2). A propos de cinq observations, nous rapportons un sc\u00e9nario particulier de l\u2019histoire naturelle de la HAA abstinente. Il s\u2019agit d\u2019une \u00e9volution mal connue, non d\u00e9crite et pourtant pr\u00e9visible.<\/p>\n<p>Description du sc\u00e9nario : La phase I est un \u00e9pisode typique de HAA s\u00e9v\u00e8re avec une fonction discriminante de Maddrey sup\u00e9rieure \u00e0 32. Il s\u2019agissait dans les cinq cas d\u2019un premier \u00e9pisode d\u2019ict\u00e8re et d\u2019une premi\u00e8re hospitalisation pour maladie h\u00e9patique. Dans trois cas, l\u2019arr\u00eat de l\u2019alcool f\u00fbt imm\u00e9diat et dans deux cas, il est survenu apr\u00e8s 11 et 13 mois. La phase II est celle de \u00ab l\u2019embellie heureuse \u00bb, l\u2019abstinence est compl\u00e8te, la biologie h\u00e9patique est normale, l\u2019ict\u00e8re et l\u2019ascite ont disparu et les diur\u00e9tiques sont arr\u00eat\u00e9s. La dur\u00e9e de cette phase f\u00fbt de 1 \u00e0 17 ans (moyenne 7.5 ans). Un malade est toujours \u00e0 cette phase \u00e9volutive. La phase III correspond \u00e0 l\u2019\u00e9mergence de l\u2019ascite. Rapidement, l\u2019ascite devient non contr\u00f4lable. A cette phase, l\u2019imagerie radiologique est typique, montrant un foie atrophique, tr\u00e8s dysmorphique, baignant dans l\u2019ascite. La biologie h\u00e9patique (bil, alb, INR) reste normale. Le Child moyen \u00e9tait de 7 et le MELD moyen \u00e9tait de 8.9. La phase IV correspond \u00e0 la d\u00e9gradation rapide avec survenue de complications comme l\u2019ascite non contr\u00f4lable, la rupture de VO, l\u2019infection et l\u2019enc\u00e9phalopathie h\u00e9patique n\u00e9cessitant des hospitalisations r\u00e9p\u00e9t\u00e9es et justifiant la proposition de transplantation h\u00e9patique. A ce stade, cependant, le MELD est toujours bas, \u00e0 une valeur moyenne de 10.3, hypoth\u00e9quant la possibilit\u00e9 de transplantation. Deux malades ont pu \u00eatre transplant\u00e9s \u00e0 l\u2019\u00e9poque du Child. Un malade est d\u00e9c\u00e9d\u00e9 en liste d\u2019attente faute d\u2019un MELD suffisamment \u00e9lev\u00e9. Un dernier malade a \u00e9t\u00e9 list\u00e9 d\u00e8s l\u2019apparition de l\u2019ascite avec un MELD de 8.5 dans l\u2019espoir d\u2019une greffe de donneur vivant.<\/p>\n<p>Conclusions : <\/p>\n<p>1\u00b0) Ce sc\u00e9nario de l\u2019histoire naturelle de la HAA est mal connu. Cette m\u00e9connaissance s\u2019explique par la survie m\u00e9diocre de la HAA s\u00e9v\u00e8re \u00e0 long terme et par la difficult\u00e9 d\u2019un suivi prolong\u00e9. <\/p>\n<p>2\u00b0) Le m\u00e9canisme de l\u2019atrophie h\u00e9patique pourrait \u00eatre l\u2019extinction parenchymateuse d\u00e9crite par Wanless (3). <\/p>\n<p>3\u00b0) Cette \u00e9volution est pr\u00e9visible et donc, d\u2019un point de vue pratique, elle implique une surveillance r\u00e9guli\u00e8re et prolong\u00e9e de la HAA s\u00e9v\u00e8re abstinente, la pr\u00e9vention de l\u2019apparition de l\u2019ascite et la proposition pr\u00e9coce pour transplantation h\u00e9patique.<\/p>\n<p>4\u00b0) L\u2019allocation d\u2019un greffon en fonction du MELD \u00ab pure et dure \u00bb comme c\u2019est le cas en Belgique, est catastrophique pour ces malades. <\/p>\n<p>(1) Mathurin, Gut 2010 ; (2) Louvet, Hepatology 2010 (Abstract) ; (3) Wanless, Hepatology 1995.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2011 Jean Henrion, Pierre Deltenre, St\u00e9phane De Maeght. Service d\u2019H\u00e9pato-Gastroent\u00e9rologie, H\u00f4pital de Jolimont, Haine-Saint-Paul, Belgique H\u00e9patologie &#8211; \u00a02011-05-19 &#8211;\u00a0CO &#8211; ________________________________ L\u2019histoire naturelle de la HAA est mieux connue gr\u00e2ce aux travaux de l\u2019\u00e9quipe lilloise. La mortalit\u00e9 \u00e0 six semaines est de l\u2019ordre de 25 % et est pr\u00e9dite par le score de Lille (1). [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[22],"class_list":["post-1946","post","type-post","status-publish","format-standard","hentry","category-hepatologie","tag-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:40:04+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente.\",\"datePublished\":\"2011-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/\"},\"wordCount\":569,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2011\"],\"articleSection\":[\"Hepatologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/\",\"name\":\"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2011-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:04+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/","og_locale":"fr_FR","og_type":"article","og_title":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2011-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:40:04+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente.","datePublished":"2011-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:04+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/"},"wordCount":569,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2011"],"articleSection":["Hepatologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/","url":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/","name":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2011-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:04+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/atrophie-hepatique-progressive-un-scenario-dramatique-mal-connu-et-pourtant-previsible-de-lhepatite-alcoolique-aigue-haa-abstinente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"Atrophie h\u00e9patique progressive : un sc\u00e9nario dramatique, mal connu et pourtant pr\u00e9visible de l\u2019h\u00e9patite alcoolique aigu\u00eb (HAA) abstinente."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1946\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=1946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}