{"id":1994,"date":"2014-10-01T01:00:00","date_gmt":"2014-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/"},"modified":"2018-10-20T18:40:12","modified_gmt":"2018-10-20T16:40:12","slug":"traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/","title":{"rendered":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP\nEnqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux."},"content":{"rendered":"<p><strong>2014<\/strong><\/p>\n<p><em>J-L Payen 1, C Barthe (1), X Causse (2), O Ink (3), C Renou (4). (1) CH Montauban, (2) CH Orl\u00e9ans, (3) CH Soissons, (4) CH d&rsquo;Hy\u00e8res<\/em><\/p>\n<p><strong>H\u00e9patologie <\/strong>&#8211; \u00a02014-04-16 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>La r\u00e9activation du virus de l\u2019h\u00e9patite B (VHB) dans diff\u00e9rentes circonstances est une r\u00e9alit\u00e9 clinique, un traitement pr\u00e9-emptif permet de l\u2019\u00e9viter ; toutefois la recherche d\u2019une infection par le VHB et la mise en place d\u2019un traitement si n\u00e9cessaire ne sont pas syst\u00e9matiquement r\u00e9alis\u00e9es par les m\u00e9decins prescripteurs de mol\u00e9cules susceptibles d\u2019entrainer une r\u00e9activation du VHB.<\/p>\n<p>But de l\u2019\u00e9tude : R\u00e9aliser une enqu\u00eate de pratique concernant le traitement pr\u00e9-emptif et \u00e9valuer l\u2019efficacit\u00e9 d\u2019une formation sur ce th\u00e8me aupr\u00e8s des m\u00e9decins prescripteurs de mol\u00e9cules susceptibles d\u2019entrainer une r\u00e9activation du VHB, dans des centres de l\u2019ANGH.<\/p>\n<p>Mat\u00e9riel et m\u00e9thode : Une enqu\u00eate de pratique et un mod\u00e8le de formation sur un support PowerPoint ont \u00e9t\u00e9 r\u00e9alis\u00e9s et valid\u00e9s par le conseil scientifique de l\u2019ANGH sur le traitement pr\u00e9-emptif et ses indications. Ces outils ont \u00e9t\u00e9 mis \u00e0 disposition des \u00e9quipes souhaitant organiser des r\u00e9unions de formation par l\u2019interm\u00e9diaire du site internet de l\u2019association. Ces r\u00e9unions s\u2019adressaient principalement aux onco-h\u00e9matologues, dermatologues, rhumatologues, pneumologues, gastro-ent\u00e9rologues. L\u2019enqu\u00eate \u00e9tait r\u00e9alis\u00e9e avant et apr\u00e8s la formation, puis th\u00e9oriquement 6 mois plus tard. Les r\u00e9unions \u00e9taient organis\u00e9es avec le soutien de BMS.<\/p>\n<p>R\u00e9sultats : 4 centres ont organis\u00e9s des r\u00e9unions en France. Ont \u00e9t\u00e9 form\u00e9s : Onco-h\u00e9matologues 26 %, dermatologues 3%, rhumatologue et pneumologue 0%, gastro-ent\u00e9rologues 56 % ; de moyenne d\u2019\u00e2ge 42,8 +\/- 13 ans. <\/p>\n<p>R\u00e9ponses aux questions de l&rsquo;enqu\u00eate :<\/p>\n<p>Voir tableau sur le fichier WORD joint <\/p>\n<p>Ces donn\u00e9es \u00e9taient ind\u00e9pendantes de la sp\u00e9cialit\u00e9 des m\u00e9decins et des centres.<\/p>\n<p>Conclusions : 1) Cette EPP \u00e9tait pertinente compte tenu de la mauvaise connaissance du probl\u00e8me de la r\u00e9activation du VHB et du traitement pr\u00e9-emptif par les m\u00e9decins prescripteurs de mol\u00e9cules susceptibles d\u2019entrainer une r\u00e9activation du VHB. 2) La cible n\u2019a pas \u00e9t\u00e9 parfaitement atteinte, les formations mobilisant trop peu les autres sp\u00e9cialit\u00e9s que les gastro-ent\u00e9rologues. 3) L\u2019enqu\u00eate n\u2019a pas \u00e9t\u00e9 compl\u00e8te car impossible \u00e0 organiser 6 mois apr\u00e8s la formation en pratique. 4) La formation est tr\u00e8s efficace lors de sa r\u00e9alisation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2014 J-L Payen 1, C Barthe (1), X Causse (2), O Ink (3), C Renou (4). (1) CH Montauban, (2) CH Orl\u00e9ans, (3) CH Soissons, (4) CH d&rsquo;Hy\u00e8res H\u00e9patologie &#8211; \u00a02014-04-16 &#8211;\u00a0CO &#8211; ________________________________ La r\u00e9activation du virus de l\u2019h\u00e9patite B (VHB) dans diff\u00e9rentes circonstances est une r\u00e9alit\u00e9 clinique, un traitement pr\u00e9-emptif permet de l\u2019\u00e9viter [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[25],"class_list":["post-1994","post","type-post","status-publish","format-standard","hentry","category-hepatologie","tag-25"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:40:12+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux.\",\"datePublished\":\"2014-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2014\"],\"articleSection\":[\"Hepatologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/\",\"name\":\"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2014-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:12+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2014-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:40:12+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux.","datePublished":"2014-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:12+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2014"],"articleSection":["Hepatologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/","url":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/","name":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2014-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:12+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/traitement-pre-emptif-a-lepreuve-de-leppenquete-de-pratiques-et-efficacite-dune-formation-dans-les-hopitaux-generaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"Traitement pr\u00e9-emptif \u00e0 l\u2019\u00e9preuve de l\u2019EPP Enqu\u00eate de pratiques et efficacit\u00e9 d\u2019une formation dans les h\u00f4pitaux g\u00e9n\u00e9raux."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=1994"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/1994\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=1994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=1994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=1994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}