{"id":2065,"date":"2017-10-01T01:00:00","date_gmt":"2017-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/"},"modified":"2018-10-20T18:40:22","modified_gmt":"2018-10-20T16:40:22","slug":"la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/","title":{"rendered":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas."},"content":{"rendered":"<p><strong>2017<\/strong><\/p>\n<p><em>Gilles Macaigne (1), Mathieu Yver (2), Pierre Lahmek (3), Christophe Locher (4), Trompette Marie (1), Dorian Dikov (2), Fran\u00e7ois Kemeny (2).<br \/>\n(1) Service de Gastro-Ent\u00e9rologie, (2) Service d\u2019anatomo-pathologie. Centre Hospitalier de Marne la Vall\u00e9e.  (3) Service de Gastro-ent\u00e9rologie. Centre hospitalier de Limeil Br\u00e9vannes. (4) Service de Gastro-ent\u00e9rologie. Centre hospitalier de Meaux<\/em><\/p>\n<p><strong>Gastroent\u00e9rologie <\/strong>&#8211; \u00a02017-04-25 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>Introduction<br \/>\nLa CE est une entit\u00e9 pathologique li\u00e9e \u00e0 une infiltration anormale de la muqueuse colique par des \u00e9osinophiles, pour laquelle il n\u2019y a pas actuellement de consensus sur les crit\u00e8res diagnostiques histologiques. Il s\u2019agit d\u2019une pathologie relativement fr\u00e9quente chez le nourrisson et l\u2019enfant, le plus souvent secondaire \u00e0 une allergie aux prot\u00e9ines du lait de vache. Chez l\u2019adulte, la CE est beaucoup plus rare et a \u00e9t\u00e9 beaucoup moins \u00e9tudi\u00e9e, seuls des cas cliniques isol\u00e9s ou de petites s\u00e9ries \u00e9tant publi\u00e9s. Il s\u2019agit d\u2019une pathologie probablement en augmentation, sous estim\u00e9e car mal connue.<\/p>\n<p>Malades et M\u00e9thodes<br \/>\nLa totalit\u00e9 des cas de CE diagnostiqu\u00e9s entre 2013 et 2016 au CH de Marne la Vall\u00e9e a \u00e9t\u00e9 collig\u00e9e. Les donn\u00e9es \u00e9pid\u00e9miologiques, cliniques, biologiques, endoscopiques, histologiques et \u00e9volutives ont \u00e9t\u00e9 recueillies prospectivement. Chaque malade a b\u00e9n\u00e9fici\u00e9 d\u2019une coloscopie totale avec biopsies recto-coliques \u00e9tag\u00e9es et il\u00e9ales, la gastroscopie n\u2019\u00e9tant r\u00e9alis\u00e9e qu\u2019\u00e0 l\u2019initiative de l\u2019investigateur.  Le diagnostic  de CE \u00e9tait port\u00e9 histologiquement en cas d\u2019augmentation du taux de polynucl\u00e9aires \u00e0 \u00e9osinophiles &gt; 20\/champ \u00e0 fort grossissement dans au moins 2 secteurs coliques (colon droit, transverse, gauche, rectum) et\/ou dans l\u2019il\u00e9on, sans autre \u00e9tiologie \u00e9voqu\u00e9e histologiquement. <\/p>\n<p>R\u00e9sultats<br \/>\n38 malades avec le diagnostic histologique de CE ont \u00e9t\u00e9 inclus (65% de femmes \u2013 \u00e2ge moyen 44,3 ans). Les indications du bilan endoscopique \u00e9taient une diarrh\u00e9e seule (74%), des douleurs abdominales sans diarrh\u00e9e (14%), des rectorragies ou un m\u00e9l\u00e9na (20%) et une an\u00e9mie ferriprive (3%). La coloscopie \u00e9tait anormale chez 37% des malades (14\/38), les l\u00e9sions retrouv\u00e9es \u00e9tant les suivantes : \u00e9ryth\u00e8me 86%, \u0153d\u00e8me 57%, \u00e9rosions 86% et ulc\u00e9rations 57% des cas. Les l\u00e9sions endoscopiques pr\u00e9dominaient au niveau du colon droit (43%) puis du colon gauche (36%). Sur le plan \u00e9tiologique, 10 (27%) malades avec une CE secondaires (2 mastocytoses, 5 maladies de crohn, 2 causes m\u00e9dicamenteuses, 2 parasitoses) et 27 (73%) une CE primitives. Parmi ces 27 malades, 12 (43%) avaient un terrain allergique connu au moment du diagnostic. Les 2 groupes de CE primitives et secondaires ont \u00e9t\u00e9 compar\u00e9s pour les caract\u00e9ristiques \u00e9pid\u00e9miologiques, cliniques, biologiques endoscopiques et histologiques.  Les r\u00e9sultats statistiques, les traitements propos\u00e9s et l\u2019\u00e9volution sous traitement des malades avec CE primitive seront pr\u00e9sent\u00e9s le jour du congr\u00e8s.<\/p>\n<p>Conclusion<br \/>\nIl s\u2019agit \u00e0 notre connaissance de la premi\u00e8re s\u00e9rie de CE de l\u2019adulte rapport\u00e9e jusqu\u2019alors. Dans notre travail, les \u00be des CE \u00e9taient primitives. Les r\u00e9sultats des comparaisons entre les CE primitives et secondaires seront pr\u00e9sent\u00e9es au congr\u00e8s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2017 Gilles Macaigne (1), Mathieu Yver (2), Pierre Lahmek (3), Christophe Locher (4), Trompette Marie (1), Dorian Dikov (2), Fran\u00e7ois Kemeny (2). (1) Service de Gastro-Ent\u00e9rologie, (2) Service d\u2019anatomo-pathologie. Centre Hospitalier de Marne la Vall\u00e9e. (3) Service de Gastro-ent\u00e9rologie. Centre hospitalier de Limeil Br\u00e9vannes. (4) Service de Gastro-ent\u00e9rologie. Centre hospitalier de Meaux Gastroent\u00e9rologie &#8211; \u00a02017-04-25 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[28],"class_list":["post-2065","post","type-post","status-publish","format-standard","hentry","category-gastroenterologie","tag-28"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:40:22+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas.\",\"datePublished\":\"2017-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2017\"],\"articleSection\":[\"Gastroenterologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/\",\"name\":\"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2017-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:22+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/","og_locale":"fr_FR","og_type":"article","og_title":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2017-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:40:22+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas.","datePublished":"2017-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:22+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2017"],"articleSection":["Gastroenterologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/","url":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/","name":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2017-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:22+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/la-colite-a-eosinophiles-ce-une-pathologie-emergente-mal-connue-a-propos-dune-serie-mono-centrique-de-37-cas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"La colite \u00e0 \u00e9osinophiles (CE), une pathologie \u00e9mergente mal connue ? \u00e0 propos d\u2019une s\u00e9rie mono-centrique de 37 cas."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=2065"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2065\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=2065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=2065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=2065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}