{"id":2082,"date":"2017-10-01T01:00:00","date_gmt":"2017-10-01T00:00:00","guid":{"rendered":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/"},"modified":"2018-10-20T18:40:25","modified_gmt":"2018-10-20T16:40:25","slug":"traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/","title":{"rendered":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES\nExp\u00e9rience Avignonnaise"},"content":{"rendered":"<p><strong>2017<\/strong><\/p>\n<p><em>B.COULIBALY, D.IMBERT, S.BELLON, S.BRAMLI, JP ARPURT<\/em><\/p>\n<p><strong>Endoscopie <\/strong>&#8211; \u00a02017-05-13 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>Les st\u00e9noses anastomotiques digestives sont fr\u00e9quentes. La reprise chirurgicale repr\u00e9sente un traitement lourd. L\u2019alternative classique est la dilatation pneumatique.<br \/>\nPour des st\u00e9noses courtes (&lt;20mm) le traitement par la mise en place d\u2019une proth\u00e8se en forme de diabolo pour pr\u00e9venir la migration pourrait \u00eatre propos\u00e9.<\/p>\n<p>Nous rapportons le cas de Mr DEDE, 86 ans<br \/>\nGastrectomie des 2\/3 il y a 25 ans<br \/>\nAEG et vomissements depuis 3 mois<br \/>\nFOGD : cancer moignon anastomotique st\u00e9nosant<br \/>\n\t  Dilatation \u00e0 vis\u00e9e palliative et pose proth\u00e8se diabolo (30\/16)<br \/>\nR\u00e9cidive des sympt\u00f4mes au bout de 4 semaines<br \/>\nTDM : migration proth\u00e8se<br \/>\nChirurgie r\u00e9cus\u00e9e car d\u00e9nutrition majeure<br \/>\nD\u00e9cision de pose d\u2019une proth\u00e8se diabolo sur mesure<br \/>\n(Film et photos)<\/p>\n<p>Prise en charge palliative chez ce patient. Evolution favorable \u00e0 2mois<br \/>\nApr\u00e8s discussion en RCP demande de l\u2019\u00e9quipe chirurgicale proposition de prise en charge de st\u00e9noses b\u00e9nignes courtes par le m\u00eame type de proth\u00e8se.<\/p>\n<p>2 proth\u00e8ses sur anastomose recto sigmo\u00efdienne (Cas et Photo)<br \/>\n1 proth\u00e8se sur st\u00e9nose post sleeve  apr\u00e8s \u00e9chec dilatation(cas et photo)<\/p>\n<p>Modalit\u00e9s : discussion m\u00e9dico chirurgicale pr\u00e9alable, information patient, proc\u00e9dure sous AG et sous CO2.<\/p>\n<p>La pose d\u2019une proth\u00e8se type diabolo sur des st\u00e9noses anastomotiques b\u00e9nignes courtes ou \u00e0 titre palliatif pourrait \u00eatre une alternative efficace en premi\u00e8re intention \u00e0 la dilatation<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2017 B.COULIBALY, D.IMBERT, S.BELLON, S.BRAMLI, JP ARPURT Endoscopie &#8211; \u00a02017-05-13 &#8211;\u00a0CO &#8211; ________________________________ Les st\u00e9noses anastomotiques digestives sont fr\u00e9quentes. La reprise chirurgicale repr\u00e9sente un traitement lourd. L\u2019alternative classique est la dilatation pneumatique. Pour des st\u00e9noses courtes (&lt;20mm) le traitement par la mise en place d\u2019une proth\u00e8se en forme de diabolo pour pr\u00e9venir la migration pourrait [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[28],"class_list":["post-2082","post","type-post","status-publish","format-standard","hentry","category-endoscopie","tag-28"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-20T16:40:25+00:00\" \/>\n<meta name=\"author\" content=\"abstracts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abstracts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/\"},\"author\":{\"name\":\"abstracts\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\"},\"headline\":\"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise\",\"datePublished\":\"2017-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2017\"],\"articleSection\":[\"Endoscopie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/\",\"name\":\"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2017-10-01T00:00:00+00:00\",\"dateModified\":\"2018-10-20T16:40:25+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/f532083854369dca4b9f509cfbad90e1\",\"name\":\"abstracts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g\",\"caption\":\"abstracts\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/abstracts\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/","og_locale":"fr_FR","og_type":"article","og_title":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2017-10-01T00:00:00+00:00","article_modified_time":"2018-10-20T16:40:25+00:00","author":"abstracts","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abstracts","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/"},"author":{"name":"abstracts","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1"},"headline":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise","datePublished":"2017-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2017"],"articleSection":["Endoscopie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/","url":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/","name":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2017-10-01T00:00:00+00:00","dateModified":"2018-10-20T16:40:25+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/traitement-endoscopique-des-stenoses-anastomotiquesexperience-avignonnaise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"TRAITEMENT ENDOSCOPIQUE DES STENOSES ANASTOMOTIQUES Exp\u00e9rience Avignonnaise"}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/f532083854369dca4b9f509cfbad90e1","name":"abstracts","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bb25d9cedd377e33f0ebc4fb5994a2f9d3e02f897704acdcc173c15b7c75253?s=96&d=mm&r=g","caption":"abstracts"},"url":"https:\/\/angh.net\/abstracts\/author\/abstracts\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2082\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=2082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=2082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}