{"id":2283,"date":"2019-12-31T19:32:06","date_gmt":"2019-12-31T18:32:06","guid":{"rendered":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/"},"modified":"2019-12-31T19:32:06","modified_gmt":"2019-12-31T18:32:06","slug":"kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/","title":{"rendered":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&rsquo;AVIGNON\nEVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS."},"content":{"rendered":"<p><strong>2019<\/strong><\/p>\n<p><em>S. BELLON, T. ANDRIANTSENO, A. RAOTO, C. BOSSHARDT, A. BENEZECH, B. COULIBALY, JP. ARPURT -SERVICE HEPATOGASTROENTEROLOGIE CENTRE HOSPITALIER D&rsquo;AVIGNON<\/em><\/p>\n<p><strong>Endoscopie <\/strong>&#8211; \u00a02019-05-16 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>INTRODUCTION : La kystogastrostomie par technique endoscopique existe depuis les ann\u00e9es 90. A partir des ann\u00e9es 2000, l&rsquo;approche \u00e9cho endoscopique a progressivement remplac\u00e9 l&rsquo;endoscopie conventionnelle dans la mesure o\u00f9 elle permet le rep\u00e9rage de la collection \u00e0 drainer. Au cours de ces ann\u00e9es, le mat\u00e9riel utilis\u00e9, notamment le mat\u00e9riel proth\u00e9tique s&rsquo;est modifi\u00e9. Nous rapportons notre exp\u00e9rience de l&rsquo;utilisation de ces diff\u00e9rentes proth\u00e8ses.<br \/>\nRESULTATS : 55 kystogastrostomies ont \u00e9t\u00e9 r\u00e9alis\u00e9es entre 2014 et 2019 par deux op\u00e9rateurs principaux. Les indications \u00e9taient des pseudo kystes aigus accompagn\u00e9s de n\u00e9crose symptomatique (infection 22 cas \/ compression digestive ou vasculaire 6 cas) ou des pseudo kystes chroniques r\u00e9tentionnels (27 cas). Le mat\u00e9riel utilis\u00e9 \u00e9tait : proth\u00e8ses double queue de cochon (PQC) dans 5 cas\/ proth\u00e8ses diabolo (PD) dans 30 cas et proth\u00e8ses d&rsquo;apposition (PA) dans 20 cas. La voie d&rsquo;abord \u00e9tait transgastrique 54 fois et transbulbaire 1 fois. La dur\u00e9e des proc\u00e9dures \u00e9tait de 54 minutes pour les PQC ; 47 minutes pour les PD et 33 minutes pour les PA. On note 4 \u00e9checs de pose (3 pour les PD, 1 pour les PA) ; et 4 complications (0 pour les PQC, 4 pour les PD,  0 pour les PA). Une seule de ces complications augmentait la dur\u00e9e du s\u00e9jour hospitalier du patient (7 jours). L&rsquo;utilisation de mat\u00e9riel compl\u00e9mentaire pendant la proc\u00e9dure \u00e9tait requise pour 4 des 30 PD et 17 des 20 PA. Le d\u00e9lai de retrait des proth\u00e8ses m\u00e9talliques \u00e9tait de 14 semaines pour les PD et 10 semaines pour les PA. Seulement 5 n\u00e9crosectomies endoscopiques ont \u00e9t\u00e9 n\u00e9cessaires. Le co\u00fbt d&rsquo;une proc\u00e9dure \u00ab\u00a0id\u00e9ale\u00a0\u00bb est de 850,00 \u20ac pour les PQC, 1510,00 \u20ac pour les PD et 2700,00 \u20ac pour les PA (auxquels il faut rajouter 280,00 \u20ac pour un pr\u00e9l\u00e8vement bact\u00e9riologique et 105,00 \u20ac pour une queue de cochon).<br \/>\nDISCUSSION : Sur les 5 derni\u00e8res ann\u00e9es, nous avons r\u00e9alis\u00e9 au Centre Hospitalier d&rsquo;Avignon, en moyenne, une kystogastrostomie par mois. L&rsquo;analyse de nos r\u00e9sultat va dans le sens d&rsquo;une proc\u00e9dure efficace et peu morbide, quelque soit le mat\u00e9riel utilis\u00e9.<br \/>\nCependant, sur ces m\u00eames ann\u00e9es, nous avons observ\u00e9 une modification de certaines de nos pratiques. Si la fr\u00e9quence d&#8217;emploi des PQC ne s&rsquo;est pas modifi\u00e9e (un cas par an pour des kystes r\u00e9tentionnels \u00ab\u00a0purs\u00a0\u00bb), en revanche, il y a eu une \u00e9volution nette dans l&rsquo;utilisation des proth\u00e8ses m\u00e9talliques. Avec une inversion des fr\u00e9quences respectives d&rsquo;utilisations : PROTHESES D&rsquo;APPOSITION : un tiers des proc\u00e9dures en 2016, la moiti\u00e9 des proc\u00e9dures en 2017 et 90 % des proc\u00e9dures en 2018-2019. En fait, la facilit\u00e9 d&rsquo;utilisation de ces derni\u00e8res (un \u00e9chec pour 20 proc\u00e9dures) et la rapidit\u00e9 d&rsquo;utilisation (33 minutes en moyenne), associ\u00e9es \u00e0 l&rsquo;absence de complication, nous a fait progressivement pr\u00e9f\u00e9rer ce mat\u00e9riel.<br \/>\nCes proth\u00e8ses posent n\u00e9anmoins deux probl\u00e8mes. Le premier est le risque h\u00e9morragique au cours des semaines qui suivent la pose, d\u00e9crit dans la litt\u00e9rature. Ceci ne s&rsquo;est jamais produit dans notre exp\u00e9rience, malgr\u00e9 un d\u00e9lai de retrait long (10 semaines). La mise en place d&rsquo;une queue de cochon \u00e0 l&rsquo;int\u00e9rieur de la proth\u00e8se d&rsquo;apposition pour \u00e9viter l&rsquo;impaction de la paroi du kyste (et donc d&rsquo;\u00e9ventuels vaisseaux) contre la collerette interne de la proth\u00e8se, a peut \u00eatre particip\u00e9 \u00e0 la pr\u00e9vention de ce risque. En effet, cette technique sugg\u00e9r\u00e9e dans les ateliers de Vid\u00e9odigest a \u00e9t\u00e9 appliqu\u00e9e dans notre centre chaque fois qu&rsquo;un vaisseau \u00e9tait visible autour de la zone de ponction (9 fois sur 20). Le deuxi\u00e8me probl\u00e8me est le co\u00fbt de ce nouveau mat\u00e9riel entre 2700,00 et 3100,00 \u20ac selon que l&rsquo;on utilise ou non du mat\u00e9riel compl\u00e9mentaire. Une partie de ce probl\u00e8me s&rsquo;est r\u00e9gl\u00e9e puisque la soci\u00e9t\u00e9 qui commercialise les PA a obtenu le remboursement du mat\u00e9riel dans certaines conditions d&rsquo;utilisation (drainage des kystes avec plus de 30 % de n\u00e9crose). L&rsquo;extension d&rsquo;autorisation aux autres indications est en attente. Il est souhaitable, par ailleurs, que le syst\u00e8me de pose de la proth\u00e8se d&rsquo;apposition puisse un jour permettre directement les pr\u00e9l\u00e8vements bact\u00e9riologiques.<br \/>\nCONCLUSION : Avec les r\u00e9serves habituelles li\u00e9es \u00e0 un nombre limit\u00e9 d&rsquo;observations, notre exp\u00e9rience sur 5 ans de la kystogastrostomie par \u00e9cho endoscopie montre qu&rsquo;il s&rsquo;agit d&rsquo;un geste reproductible et peu morbide peu importe le mat\u00e9riel utilis\u00e9. M\u00eame s&rsquo;il faut v\u00e9rifier dans le temps, leur faible taux de complications, la facilit\u00e9 d&rsquo;utilisation des PROTHESES D&rsquo;APPOSITION nous fait actuellement les utiliser en premi\u00e8re intention ; malgr\u00e9 un co\u00fbt \u00e9lev\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2019 S. BELLON, T. ANDRIANTSENO, A. RAOTO, C. BOSSHARDT, A. BENEZECH, B. COULIBALY, JP. ARPURT -SERVICE HEPATOGASTROENTEROLOGIE CENTRE HOSPITALIER D&rsquo;AVIGNON Endoscopie &#8211; \u00a02019-05-16 &#8211;\u00a0CO &#8211; ________________________________ INTRODUCTION : La kystogastrostomie par technique endoscopique existe depuis les ann\u00e9es 90. A partir des ann\u00e9es 2000, l&rsquo;approche \u00e9cho endoscopique a progressivement remplac\u00e9 l&rsquo;endoscopie conventionnelle dans la mesure o\u00f9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[30],"class_list":["post-2283","post","type-post","status-publish","format-standard","hentry","category-endoscopie","tag-30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&#039;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&#039;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-31T18:32:06+00:00\" \/>\n<meta name=\"author\" content=\"Bruno Lesgourgues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Lesgourgues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/\"},\"author\":{\"name\":\"Bruno Lesgourgues\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\"},\"headline\":\"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&rsquo;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS.\",\"datePublished\":\"2019-12-31T18:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/\"},\"wordCount\":830,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2019\"],\"articleSection\":[\"Endoscopie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/\",\"name\":\"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D'AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2019-12-31T18:32:06+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&rsquo;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\",\"name\":\"Bruno Lesgourgues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"caption\":\"Bruno Lesgourgues\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/blesgourgues-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D'AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D'AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2019-12-31T18:32:06+00:00","author":"Bruno Lesgourgues","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bruno Lesgourgues","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/"},"author":{"name":"Bruno Lesgourgues","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d"},"headline":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&rsquo;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS.","datePublished":"2019-12-31T18:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/"},"wordCount":830,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2019"],"articleSection":["Endoscopie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/","url":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/","name":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D'AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2019-12-31T18:32:06+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/kystogastrostomie-au-centre-hospitalier-davignonevaluation-des-pratiques-a-partir-de-55-cas-sur-5-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"KYSTOGASTROSTOMIE AU CENTRE HOSPITALIER D&rsquo;AVIGNON EVALUATION DES PRATIQUES A PARTIR DE 55 CAS SUR 5 ANS."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d","name":"Bruno Lesgourgues","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","caption":"Bruno Lesgourgues"},"url":"https:\/\/angh.net\/abstracts\/author\/blesgourgues-2\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=2283"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2283\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=2283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=2283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=2283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}