{"id":2335,"date":"2020-09-25T22:13:28","date_gmt":"2020-09-25T20:13:28","guid":{"rendered":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/"},"modified":"2020-09-25T22:13:28","modified_gmt":"2020-09-25T20:13:28","slug":"amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/","title":{"rendered":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par  M\u00e9salazine. \u00c9tude QUARTZ."},"content":{"rendered":"<p><strong>2020<\/strong><\/p>\n<p><em>Thierry Paupard1, Florent Gonzalez2, Laurent Siprhoudhis3, Laurent Peyrin-Biroulet4<br \/>\n1Centre Hospitalier de Dunkerque, Dunkerque, France<br \/>\n2Cabinet d&rsquo;H\u00e9pato Gastroent\u00e9rologie, N\u00eemes, France<br \/>\n3CHU Pontchaillou, Rennes, France<br \/>\n4CHU Brabois, Vand\u0153uvre-l\u00e8s-Nancy<\/em><\/p>\n<p><strong>Gastroent\u00e9rologie <\/strong>&#8211; \u00a02020-07-05 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>Introduction<br \/>\nIl n\u2019existe pas de donn\u00e9es scientifiques solides ayant analys\u00e9 de fa\u00e7on combin\u00e9e la qualit\u00e9 de vie, le handicap fonctionnel et la continence des patients souffrant d\u2019une RCH distale. Il s\u2019agit de la premi\u00e8re \u00e9tude prospective dans cette situation.<br \/>\nPatients et m\u00e9thodes<br \/>\n\u00c9tude observationnelle, prospective et multicentrique impliquant des gastro-ent\u00e9rologues hospitaliers et lib\u00e9raux, men\u00e9e chez des patients atteints de rectite ou recto-sigmo\u00efdite basse (<20 cm) active d\u2019intensit\u00e9 l\u00e9g\u00e8re \u00e0 mod\u00e9r\u00e9e (score Mayo \u22653 et \u226410), et trait\u00e9s par M\u00e9salazine en traitement d\u2019induction de la pouss\u00e9e. Les patients ont \u00e9t\u00e9 suivis pendant 12 mois (\u00b12 mois). Le crit\u00e8re de jugement principal (qualit\u00e9 de vie) \u00e9tait \u00e9valu\u00e9 par le questionnaire SIBDQ \u00e0 8 semaines (\u00b14 semaines) de traitement. Le handicap fonctionnel et l\u2019incontinence f\u00e9cale li\u00e9s \u00e0 la maladie ont \u00e9t\u00e9 \u00e9valu\u00e9s respectivement \u00e0 l\u2019aide des questionnaires IBD-DI et de Cleveland.\nR\u00e9sultats \nDe d\u00e9cembre 2015 \u00e0 Novembre 2016, 117 patients ont \u00e9t\u00e9 inclus. Les donn\u00e9es de 93 patients ont fait l\u2019objet d\u2019une analyse dont les principaux r\u00e9sultats sont rapport\u00e9s dans le tableau 1. A 8 semaines, 76 (81%) patients \u00e9taient en r\u00e9mission clinique avec une am\u00e9lioration moyenne du score SIBDQ de 6,7\u00b17,1 points (p<0.001). L\u2019observance au traitement au cours de la p\u00e9riode d\u2019induction \u00e9tait imparfaite chez 76 (82%) patients: 17 (18%) patients ont arr\u00eat\u00e9 le traitement pr\u00e9matur\u00e9ment avant la huiti\u00e8me semaine (formulation rectale chez tous). A l\u2019issue de la phase d\u2019induction, 72 (77%) patients ont eu un traitement de maintenance. Onze (12%) patients ont rapport\u00e9 un \u00e9v\u00e8nement ind\u00e9sirable au cours de l\u2019\u00e9tude, mais aucun n\u2019\u00e9tait li\u00e9 au traitement.\nConclusion\nChez des patients atteints d\u2019une forme distale de RCH et trait\u00e9s par  M\u00e9salazine, la qualit\u00e9 de vie, le handicap fonctionnel et la continence s\u2019am\u00e9liorent \u00e0 8 semaines en d\u00e9pit d\u2019une observance sous optimale.\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2020 Thierry Paupard1, Florent Gonzalez2, Laurent Siprhoudhis3, Laurent Peyrin-Biroulet4 1Centre Hospitalier de Dunkerque, Dunkerque, France 2Cabinet d&rsquo;H\u00e9pato Gastroent\u00e9rologie, N\u00eemes, France 3CHU Pontchaillou, Rennes, France 4CHU Brabois, Vand\u0153uvre-l\u00e8s-Nancy Gastroent\u00e9rologie &#8211; \u00a02020-07-05 &#8211;\u00a0CO &#8211; ________________________________ Introduction Il n\u2019existe pas de donn\u00e9es scientifiques solides ayant analys\u00e9 de fa\u00e7on combin\u00e9e la qualit\u00e9 de vie, le handicap fonctionnel et la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-2335","post","type-post","status-publish","format-standard","hentry","category-gastroenterologie","tag-31"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-25T20:13:28+00:00\" \/>\n<meta name=\"author\" content=\"Bruno Lesgourgues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Lesgourgues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/\"},\"author\":{\"name\":\"Bruno Lesgourgues\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\"},\"headline\":\"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ.\",\"datePublished\":\"2020-09-25T20:13:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/\"},\"wordCount\":139,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2020\"],\"articleSection\":[\"Gastroenterologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/\",\"name\":\"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2020-09-25T20:13:28+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\",\"name\":\"Bruno Lesgourgues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"caption\":\"Bruno Lesgourgues\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/blesgourgues-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/","og_locale":"fr_FR","og_type":"article","og_title":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2020-09-25T20:13:28+00:00","author":"Bruno Lesgourgues","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bruno Lesgourgues","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/"},"author":{"name":"Bruno Lesgourgues","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d"},"headline":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ.","datePublished":"2020-09-25T20:13:28+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/"},"wordCount":139,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2020"],"articleSection":["Gastroenterologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/","url":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/","name":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2020-09-25T20:13:28+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/amelioration-de-la-qualite-de-vie-et-de-la-continence-des-patients-atteints-de-rch-distale-traites-par-mesalazine-etude-quartz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"Am\u00e9lioration de la qualit\u00e9 de vie et de la continence des patients atteints de RCH distale, trait\u00e9s par M\u00e9salazine. \u00c9tude QUARTZ."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d","name":"Bruno Lesgourgues","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","caption":"Bruno Lesgourgues"},"url":"https:\/\/angh.net\/abstracts\/author\/blesgourgues-2\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=2335"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2335\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=2335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=2335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=2335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}