{"id":2344,"date":"2020-09-25T22:14:03","date_gmt":"2020-09-25T20:14:03","guid":{"rendered":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/"},"modified":"2020-09-25T22:14:03","modified_gmt":"2020-09-25T20:14:03","slug":"correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs","status":"publish","type":"post","link":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/","title":{"rendered":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs."},"content":{"rendered":"<p><strong>2020<\/strong><\/p>\n<p><em>L. Costes, I. Rosa, M. Bani, S. Bendaoud, C. Somsouk, A. Wampach, M. Vidon, T. Lons, AC. Lesage, B. Pellat, D. Gillot, H. Hag\u00e8ge<\/em><\/p>\n<p><strong>Endoscopie <\/strong>&#8211; \u00a02020-07-13 &#8211;\u00a0CO &#8211;<\/p>\n<p>________________________________<\/p>\n<p>L\u2019ESGE recommande que tout polype soit d\u00e9crit selon son aspect macroscopique  dans la classification de Paris. La classification CONECCT est largement utilis\u00e9e mais non encore recommand\u00e9e par les soci\u00e9t\u00e9s savantes pour une utilisation syst\u00e9matique. Cette classification a l\u2019avantage de r\u00e9sumer en seul tableau des classifications parfois complexes d\u2019utilisation. En pratique courante cette classification tend \u00e0 \u00eatre la premi\u00e8re utilis\u00e9e. L\u2019utilisation de cette classification n\u00e9cessite une formation sp\u00e9cifique des endoscopistes. Dans le service nous avons d\u00e9cid\u00e9 en 2019 de g\u00e9n\u00e9raliser l\u2019utilisation des classifications Paris et CONECCT pour tout polype apr\u00e8s formation de l\u2019\u00e9quipe (deux sessions en mai 2018 et f\u00e9vrier 2019).<br \/>\nNous avons ensuite \u00e9valu\u00e9 le nombre de polypes d\u00e9crits selon Paris et CONECCT et la corr\u00e9lation entre la classification CONNECT et l\u2019histologie. Il s\u2019agit d\u2019une \u00e9tude r\u00e9trospective conduite dans le centre d\u2019endoscopie digestive du CHI de Cr\u00e9teil du 1ier janvier 2020 au 16 mars 2020. L\u2019\u00e9tude a port\u00e9e sur 300 polypes cons\u00e9cutifs sur 138 coloscopies.<br \/>\nLa taille moyenne des polypes \u00e9tait de 6.8mm en moyenne (de 1 \u00e0 50mm). La classification de Paris \u00e9tait pr\u00e9sente pour 79% des polypes et celle de CONECCT pour 92%.  L\u2019\u00e9tude de la corr\u00e9lation CONECCT avec l\u2019histologie a donc port\u00e9 sur 276 polypes.<br \/>\nAu total 58% des polypes \u00e9taient bien class\u00e9s selon CONECCT. Il existait une classification CONECCT correcte pour 41% des polypes hyperplasiques, 24% des polypes festonn\u00e9s, 70% des polypes ad\u00e9nomateux de bas grade et 67% des polypes ad\u00e9nomateux de haut grade et 100% pour les cancers invasifs. Les caract\u00e9ristiques des polypes figurent sur le tableau 1<br \/>\nConclusion :<br \/>\nLa classification des polypes est r\u00e9alis\u00e9e syst\u00e9matiquement par l\u2019\u00e9quipe depuis 2 ans. La corr\u00e9lation entre l\u2019histologie et la classification CONECCT reste insuffisante malgr\u00e9 une formation de l\u2019\u00e9quipe. D\u2019autres moyens de formation compl\u00e9mentaire devront \u00eatre mis en place de fa\u00e7on \u00e0 am\u00e9liorer la caract\u00e9risation des polypes selon CONECCT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2020 L. Costes, I. Rosa, M. Bani, S. Bendaoud, C. Somsouk, A. Wampach, M. Vidon, T. Lons, AC. Lesage, B. Pellat, D. Gillot, H. Hag\u00e8ge Endoscopie &#8211; \u00a02020-07-13 &#8211;\u00a0CO &#8211; ________________________________ L\u2019ESGE recommande que tout polype soit d\u00e9crit selon son aspect macroscopique dans la classification de Paris. La classification CONECCT est largement utilis\u00e9e mais non [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[31],"class_list":["post-2344","post","type-post","status-publish","format-standard","hentry","category-endoscopie","tag-31"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH<\/title>\n<meta name=\"description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"og:description\" content=\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/\" \/>\n<meta property=\"og:site_name\" content=\"Abstracts des congr\u00e8s de l&#039;ANGH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ANGH-2136322560030484\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-25T20:14:03+00:00\" \/>\n<meta name=\"author\" content=\"Bruno Lesgourgues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Lesgourgues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/\"},\"author\":{\"name\":\"Bruno Lesgourgues\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\"},\"headline\":\"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs.\",\"datePublished\":\"2020-09-25T20:14:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/\"},\"wordCount\":388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"keywords\":[\"2020\"],\"articleSection\":[\"Endoscopie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/\",\"name\":\"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\"},\"datePublished\":\"2020-09-25T20:14:03+00:00\",\"description\":\"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#website\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"name\":\"Abstracts des congr\u00e8s de l&#039;ANGH\",\"description\":\"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#organization\",\"name\":\"ANGH\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"contentUrl\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/logo_angh_2018_-48px.jpg\",\"width\":48,\"height\":18,\"caption\":\"ANGH\"},\"image\":{\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ANGH-2136322560030484\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/#\\\/schema\\\/person\\\/d70d83701c6dda5f93e12e8bafca7d7d\",\"name\":\"Bruno Lesgourgues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g\",\"caption\":\"Bruno Lesgourgues\"},\"url\":\"https:\\\/\\\/angh.net\\\/abstracts\\\/author\\\/blesgourgues-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/","og_locale":"fr_FR","og_type":"article","og_title":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH","og_description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","og_url":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/","og_site_name":"Abstracts des congr\u00e8s de l&#039;ANGH","article_publisher":"https:\/\/www.facebook.com\/ANGH-2136322560030484\/","article_published_time":"2020-09-25T20:14:03+00:00","author":"Bruno Lesgourgues","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bruno Lesgourgues","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/#article","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/"},"author":{"name":"Bruno Lesgourgues","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d"},"headline":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs.","datePublished":"2020-09-25T20:14:03+00:00","mainEntityOfPage":{"@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/"},"wordCount":388,"commentCount":0,"publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"keywords":["2020"],"articleSection":["Endoscopie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/","url":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/","name":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs. - Abstracts des congr\u00e8s de l&#039;ANGH","isPartOf":{"@id":"https:\/\/angh.net\/abstracts\/#website"},"datePublished":"2020-09-25T20:14:03+00:00","description":"ANGH R\u00e9sum\u00e9s congr\u00e8s H\u00e9patologie Gastroent\u00e9romogie Hepatology Gastroenterology Etudes cliniques Clinical study","breadcrumb":{"@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/angh.net\/abstracts\/correlation-entre-classification-de-conecct-et-histologie-des-polypes-coliques-resultats-sur-une-serie-monocentrique-retrospective-de-300-polypes-consecutifs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angh.net\/abstracts\/"},{"@type":"ListItem","position":2,"name":"Corr\u00e9lation entre classification de CONECCT et histologie des polypes coliques : R\u00e9sultats sur une s\u00e9rie monocentrique r\u00e9trospective de 300 polypes cons\u00e9cutifs."}]},{"@type":"WebSite","@id":"https:\/\/angh.net\/abstracts\/#website","url":"https:\/\/angh.net\/abstracts\/","name":"Abstracts des congr\u00e8s de l&#039;ANGH","description":"Base de donn\u00e9es des abstracts du congr\u00e8s depuis 2003","publisher":{"@id":"https:\/\/angh.net\/abstracts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angh.net\/abstracts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/angh.net\/abstracts\/#organization","name":"ANGH","url":"https:\/\/angh.net\/abstracts\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/","url":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","contentUrl":"https:\/\/angh.net\/abstracts\/wp-content\/uploads\/sites\/2\/2018\/10\/logo_angh_2018_-48px.jpg","width":48,"height":18,"caption":"ANGH"},"image":{"@id":"https:\/\/angh.net\/abstracts\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ANGH-2136322560030484\/"]},{"@type":"Person","@id":"https:\/\/angh.net\/abstracts\/#\/schema\/person\/d70d83701c6dda5f93e12e8bafca7d7d","name":"Bruno Lesgourgues","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c737979cf1cff53a280fef17e77a5e495d143e87a53eee6fcc0b272bb973c75?s=96&d=mm&r=g","caption":"Bruno Lesgourgues"},"url":"https:\/\/angh.net\/abstracts\/author\/blesgourgues-2\/"}]}},"_links":{"self":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/comments?post=2344"}],"version-history":[{"count":0,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/posts\/2344\/revisions"}],"wp:attachment":[{"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/media?parent=2344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/categories?post=2344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angh.net\/abstracts\/wp-json\/wp\/v2\/tags?post=2344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}